{"id":5579,"count":1,"description":"","link":"https:\/\/onberita.com\/index.php\/tag\/spanyol-lolos-final-piala-dunia\/","name":"Spanyol lolos final Piala Dunia","slug":"spanyol-lolos-final-piala-dunia","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spanyol lolos final Piala Dunia Arsip - On Berita<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onberita.com\/index.php\/tag\/spanyol-lolos-final-piala-dunia\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spanyol lolos final Piala Dunia Arsip - On Berita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onberita.com\/index.php\/tag\/spanyol-lolos-final-piala-dunia\/\" \/>\n<meta property=\"og:site_name\" content=\"On Berita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/onberita.com\\\/index.php\\\/tag\\\/spanyol-lolos-final-piala-dunia\\\/\",\"url\":\"https:\\\/\\\/onberita.com\\\/index.php\\\/tag\\\/spanyol-lolos-final-piala-dunia\\\/\",\"name\":\"Spanyol lolos final Piala Dunia Arsip - On Berita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onberita.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onberita.com\\\/index.php\\\/tag\\\/spanyol-lolos-final-piala-dunia\\\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onberita.com\\\/index.php\\\/tag\\\/spanyol-lolos-final-piala-dunia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Beranda\",\"item\":\"https:\\\/\\\/onberita.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spanyol lolos final Piala Dunia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onberita.com\\\/#website\",\"url\":\"https:\\\/\\\/onberita.com\\\/\",\"name\":\"On Berita\",\"description\":\"Mengabarkan Kebenaran\",\"publisher\":{\"@id\":\"https:\\\/\\\/onberita.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onberita.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onberita.com\\\/#organization\",\"name\":\"On Berita\",\"url\":\"https:\\\/\\\/onberita.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/onberita.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onberita.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Peta-Indonesia.png\",\"contentUrl\":\"https:\\\/\\\/onberita.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Peta-Indonesia.png\",\"width\":1411,\"height\":550,\"caption\":\"On Berita\"},\"image\":{\"@id\":\"https:\\\/\\\/onberita.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spanyol lolos final Piala Dunia Arsip - On Berita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onberita.com\/index.php\/tag\/spanyol-lolos-final-piala-dunia\/","og_locale":"id_ID","og_type":"article","og_title":"Spanyol lolos final Piala Dunia Arsip - On Berita","og_url":"https:\/\/onberita.com\/index.php\/tag\/spanyol-lolos-final-piala-dunia\/","og_site_name":"On Berita","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/onberita.com\/index.php\/tag\/spanyol-lolos-final-piala-dunia\/","url":"https:\/\/onberita.com\/index.php\/tag\/spanyol-lolos-final-piala-dunia\/","name":"Spanyol lolos final Piala Dunia Arsip - On Berita","isPartOf":{"@id":"https:\/\/onberita.com\/#website"},"breadcrumb":{"@id":"https:\/\/onberita.com\/index.php\/tag\/spanyol-lolos-final-piala-dunia\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/onberita.com\/index.php\/tag\/spanyol-lolos-final-piala-dunia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Beranda","item":"https:\/\/onberita.com\/"},{"@type":"ListItem","position":2,"name":"Spanyol lolos final Piala Dunia"}]},{"@type":"WebSite","@id":"https:\/\/onberita.com\/#website","url":"https:\/\/onberita.com\/","name":"On Berita","description":"Mengabarkan Kebenaran","publisher":{"@id":"https:\/\/onberita.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onberita.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/onberita.com\/#organization","name":"On Berita","url":"https:\/\/onberita.com\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/onberita.com\/#\/schema\/logo\/image\/","url":"https:\/\/onberita.com\/wp-content\/uploads\/2025\/03\/Peta-Indonesia.png","contentUrl":"https:\/\/onberita.com\/wp-content\/uploads\/2025\/03\/Peta-Indonesia.png","width":1411,"height":550,"caption":"On Berita"},"image":{"@id":"https:\/\/onberita.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/onberita.com\/index.php\/wp-json\/wp\/v2\/tags\/5579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onberita.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/onberita.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/onberita.com\/index.php\/wp-json\/wp\/v2\/posts?tags=5579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}